{"id":15281,"date":"2023-05-22T19:01:22","date_gmt":"2023-05-22T19:01:22","guid":{"rendered":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/produto\/esfignomanometro-heine-gamma-g5-kit\/"},"modified":"2023-05-22T19:01:22","modified_gmt":"2023-05-22T19:01:22","slug":"esfignomanometro-heine-gamma-g5-kit","status":"publish","type":"product","link":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/produto\/esfignomanometro-heine-gamma-g5-kit\/","title":{"rendered":"Esfignoman\u00f3metro HEINE GAMMA\u00ae G5 Kit"},"content":{"rendered":"<p>O esfigmoman\u00f3metro padr\u00e3o HEINE. <span style=\"font-family: &quot;Roboto Condensed&quot;, sans-serif; font-size: 14px;\">Bra\u00e7adeira Adulto, Adulto pequeno e crian\u00e7a<\/span>. \u00c0 prova de choque. Sem l\u00e1tex<br \/>\nV\u00e1lvula de libera\u00e7\u00e3o de ar exclusiva. Corpo superior met\u00e1lico. &nbsp;Prote\u00e7\u00e3o de vidro e ponteiro atrav\u00e9s de um anel para absor\u00e7\u00e3o de choques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O esfigmoman\u00f3metro padr\u00e3o HEINE. <span style=\"font-family: &quot;Roboto Condensed&quot;, sans-serif; font-size: 14px;\">Bra\u00e7adeira Adulto, Adulto pequeno e crian\u00e7a<\/span>. \u00c0 prova de choque. Sem l\u00e1tex<br \/>\nV\u00e1lvula de libera\u00e7\u00e3o de ar exclusiva. Corpo superior met\u00e1lico. &nbsp;Prote\u00e7\u00e3o de vidro e ponteiro atrav\u00e9s de um anel para absor\u00e7\u00e3o de choques.<\/p>\n","protected":false},"featured_media":15282,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[110,129],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product\/15281"}],"collection":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/comments?post=15281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/media\/15282"}],"wp:attachment":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/media?parent=15281"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product_cat?post=15281"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product_tag?post=15281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}