{"id":14404,"date":"2023-04-12T09:15:26","date_gmt":"2023-04-12T09:15:26","guid":{"rendered":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/produto\/prestige-ncd-tromner-reflex-hammer-black\/"},"modified":"2023-04-12T09:15:26","modified_gmt":"2023-04-12T09:15:26","slug":"prestige-ncd-tromner-reflex-hammer-black","status":"publish","type":"product","link":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/produto\/prestige-ncd-tromner-reflex-hammer-black\/","title":{"rendered":"Prestige\/NCD Tromner Reflex Hammer &#8211; Black"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product\/14404"}],"collection":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/comments?post=14404"}],"wp:attachment":[{"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/media?parent=14404"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product_cat?post=14404"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/estetoscopio.digitalpath.pt\/estetoscopio\/wp-json\/wp\/v2\/product_tag?post=14404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}